{"id":2880,"date":"2023-06-09T07:23:58","date_gmt":"2023-06-09T07:23:58","guid":{"rendered":"https:\/\/nelvaresort.com\/?page_id=2880"},"modified":"2026-05-01T17:18:55","modified_gmt":"2026-05-01T17:18:55","slug":"servicios-e-instalaciones","status":"publish","type":"page","link":"https:\/\/nelvaresort.com\/en\/servicios-e-instalaciones\/","title":{"rendered":"Services and facilities"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2880\" class=\"elementor elementor-2880\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bf43c31 elementor-section-full_width elementor-section-height-min-height hero-lcp-wrapper elementor-section-height-default elementor-section-items-middle\" data-id=\"4bf43c31\" data-element_type=\"section\" data-e-type=\"section\" decoding=\"async\" data-no-lazy=\"1\" fetchpriority=\"high\" loading=\"eager\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fdaa24\" data-id=\"7fdaa24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2bd1bf elementor-absolute elementor-widget-mobile__width-auto elementor-widget elementor-widget-heading\" data-id=\"f2bd1bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Services and facilities<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d1719a4 elementor-absolute elementor-widget-mobile__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"2d1719a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>You can enjoy our pool and garden area or have a drink at the Nelva Bar Restaurant<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7762a675 elementor-widget__width-initial hero-lcp elementor-widget elementor-widget-image\" data-id=\"7762a675\" data-element_type=\"widget\" data-e-type=\"widget\" decoding=\"async\" data-no-lazy=\"1\" fetchpriority=\"high\" loading=\"eager\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-scaled.jpg\" class=\"attachment-full size-full wp-image-4576\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-scaled.jpg 2560w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-300x200.jpg 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-1024x683.jpg 1024w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-768x512.jpg 768w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-1536x1024.jpg 1536w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-2048x1365.jpg 2048w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-18x12.jpg 18w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-600x400.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d3e48ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d3e48ca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-144523a6\" data-id=\"144523a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72f395bb elementor-widget elementor-widget-heading\" data-id=\"72f395bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/booking.avirato.com\/?code=49919346\">Web offer starting from 5% all apartments<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5f0bbb elementor-reverse-tablet elementor-reverse-mobile elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5f0bbb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-916cd4b\" data-id=\"916cd4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92d694f elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image-box\" data-id=\"92d694f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">Nelva Resort<\/h2><p class=\"elementor-image-box-description\">At Nelva Resort we offer you a pleasant and spacious environment so that you can enjoy your stay. <br>\n<br>\nWe have several corners and rooms in the common areas, designed to relax and have a pleasant time with family, friends or as a couple. The little ones have a play area ideal for them, next to the bar-restaurant.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09abb12 elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image-box\" data-id=\"09abb12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">Swimming pool and solarium<\/h2><p class=\"elementor-image-box-description\">In the central area, next to the large terrace, we find the swimming pool. The perfect place to rest, sunbathe or cool off with a drink, surrounded by comfortable hammocks, sun loungers and umbrellas. <br><br>\n\nWe also have a shallower area inside the pool, so that children can enjoy it without having to leave the complex.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a75cee elementor-align-left elementor-widget__width-initial elementor-mobile-align-left elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"9a75cee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/reservar\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Reserve room<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-53fc916\" data-id=\"53fc916\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32581ed elementor-widget elementor-widget-image\" data-id=\"32581ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_2303-1024x683.jpg\" class=\"attachment-large size-large wp-image-4574\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_2303-1024x683.jpg 1024w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_2303-300x200.jpg 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_2303-768x512.jpg 768w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_2303-1536x1024.jpg 1536w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_2303-2048x1365.jpg 2048w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_2303-18x12.jpg 18w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_2303-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ae9ebd elementor-widget elementor-widget-image\" data-id=\"0ae9ebd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-1024x683.jpg\" class=\"attachment-large size-large wp-image-4576\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-1024x683.jpg 1024w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-300x200.jpg 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-768x512.jpg 768w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-1536x1024.jpg 1536w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-2048x1365.jpg 2048w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-18x12.jpg 18w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1277-2025-07-08T13_01_56.388-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f295f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f295f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a9c311e\" data-id=\"a9c311e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b346ff0 elementor-widget elementor-widget-heading\" data-id=\"b346ff0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services Nelva Resort<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-22b9b6a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"22b9b6a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-eaf2f01\" data-id=\"eaf2f01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8c0506 elementor-widget elementor-widget-image\" data-id=\"f8c0506\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/senal-wifi-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-2674\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/senal-wifi-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/senal-wifi-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/senal-wifi-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/senal-wifi-100x100.png 100w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/senal-wifi.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c69de7 elementor-widget elementor-widget-text-editor\" data-id=\"2c69de7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Free WIFI<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-a9b14af\" data-id=\"a9b14af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d24ab6a elementor-widget elementor-widget-image\" data-id=\"d24ab6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/swimming-pool.png\" class=\"attachment-large size-large wp-image-3197\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/swimming-pool.png 512w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/swimming-pool-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/swimming-pool-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/swimming-pool-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/swimming-pool-100x100.png 100w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-782b3e0 elementor-widget elementor-widget-text-editor\" data-id=\"782b3e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Swimming pool and solarium<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-ff3c04a\" data-id=\"ff3c04a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37be596 elementor-widget elementor-widget-image\" data-id=\"37be596\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/tarjeta-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-2676\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/tarjeta-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/tarjeta-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/tarjeta-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/tarjeta-100x100.png 100w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/tarjeta.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d43e2a3 elementor-widget elementor-widget-text-editor\" data-id=\"d43e2a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Payment Check-in<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-513e1f6\" data-id=\"513e1f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a27d484 elementor-widget elementor-widget-image\" data-id=\"a27d484\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/descuento-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-2677\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/descuento-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/descuento-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/descuento-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/descuento-100x100.png 100w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/descuento.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-504a0d4 elementor-widget elementor-widget-text-editor\" data-id=\"504a0d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Exclusive Web Offers<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-f878601 elementor-hidden-mobile\" data-id=\"f878601\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59c457e elementor-widget elementor-widget-image\" data-id=\"59c457e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/tray.png\" class=\"attachment-large size-large wp-image-3200\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/tray.png 512w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/tray-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/tray-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/tray-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/tray-100x100.png 100w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4cb508 elementor-widget elementor-widget-text-editor\" data-id=\"e4cb508\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Bar \u2013 Restaurant with terrace<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3c205f0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3c205f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-20f5e5f\" data-id=\"20f5e5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70e96cd elementor-widget elementor-widget-image\" data-id=\"70e96cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/desayuno-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-2678\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/desayuno-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/desayuno-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/desayuno-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/desayuno-100x100.png 100w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/desayuno.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6027dc6 elementor-widget elementor-widget-text-editor\" data-id=\"6027dc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Buffet Breakfast<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-d76dd78\" data-id=\"d76dd78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0110276 elementor-widget elementor-widget-image\" data-id=\"0110276\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/estacionamiento-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-2679\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/estacionamiento-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/estacionamiento-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/estacionamiento-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/estacionamiento-100x100.png 100w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/estacionamiento.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccc4303 elementor-widget elementor-widget-text-editor\" data-id=\"ccc4303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Outdoor Parking<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-6a954b4\" data-id=\"6a954b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d71c27 elementor-widget elementor-widget-image\" data-id=\"9d71c27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/padres-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-2680\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/padres-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/padres-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/padres-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/padres-100x100.png 100w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/padres.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6241a12 elementor-widget elementor-widget-text-editor\" data-id=\"6241a12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Perfect for families or couples<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-cd76666\" data-id=\"cd76666\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef7b4c8 elementor-widget elementor-widget-image\" data-id=\"ef7b4c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/kitchen.png\" class=\"attachment-large size-large wp-image-3198\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/kitchen.png 512w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/kitchen-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/kitchen-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/kitchen-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/kitchen-100x100.png 100w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-430802c elementor-widget elementor-widget-text-editor\" data-id=\"430802c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Apartments with living room and kitchen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-7049a7b elementor-hidden-mobile\" data-id=\"7049a7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9985ff5 elementor-widget elementor-widget-image\" data-id=\"9985ff5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/balcony.png\" class=\"attachment-large size-large wp-image-3199\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/balcony.png 512w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/balcony-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/balcony-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/balcony-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/balcony-100x100.png 100w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b4a64e elementor-widget elementor-widget-text-editor\" data-id=\"9b4a64e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Apartments with balcony or terrace<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-92de9d9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"92de9d9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-fb39369\" data-id=\"fb39369\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-973565f elementor-widget elementor-widget-image\" data-id=\"973565f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/snow-icon-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-2910\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/snow-icon-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/snow-icon-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/snow-icon-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/snow-icon-100x100.png 100w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/snow-icon.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-802123d elementor-widget elementor-widget-text-editor\" data-id=\"802123d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Air-conditioning<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-4506b6a\" data-id=\"4506b6a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5145632 elementor-widget elementor-widget-image\" data-id=\"5145632\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/coctel-icon-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-2908\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/coctel-icon-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/coctel-icon-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/coctel-icon-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/coctel-icon-100x100.png 100w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/coctel-icon.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f51f27 elementor-widget elementor-widget-text-editor\" data-id=\"2f51f27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Live concerts on the terrace<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-163efed\" data-id=\"163efed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f09e779 elementor-widget elementor-widget-image\" data-id=\"f09e779\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/no-pets-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-3075\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/no-pets-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/no-pets-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/no-pets-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/no-pets-100x100.png 100w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/no-pets.png 512w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1a5882 elementor-widget elementor-widget-text-editor\" data-id=\"f1a5882\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">no pets<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-41051c8\" data-id=\"41051c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b7fc57 elementor-widget elementor-widget-image\" data-id=\"0b7fc57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2022\/09\/users-solid.svg\" class=\"attachment-large size-large wp-image-1790\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27fb307 elementor-widget elementor-widget-text-editor\" data-id=\"27fb307\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Multilingual Staff<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-10ce74f elementor-hidden-mobile\" data-id=\"10ce74f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4eb8b4f elementor-widget elementor-widget-image\" data-id=\"4eb8b4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/jardin.png\" class=\"attachment-large size-large wp-image-2681\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/jardin.png 512w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/jardin-300x300.png 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/jardin-150x150.png 150w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/jardin-12x12.png 12w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/jardin-100x100.png 100w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b287a6 elementor-widget elementor-widget-text-editor\" data-id=\"6b287a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Tourist information<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bead9d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bead9d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c77f381\" data-id=\"c77f381\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e0e284 elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image-box\" data-id=\"5e0e284\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">Flats<\/h2><p class=\"elementor-image-box-description\">We have 60 fully equipped apartments, with 1, 2 or 3 bedrooms. <br><br>\n\nThey all have a kitchen, full bathroom, living room, prepared rooms and a large terrace or a large balcony.<br><br>\n\nThe apartments include everything you need to enjoy your stay in the best possible way, such as air conditioning, Wi-Fi, flat-screen TV, furniture and various utensils.<br><br>\n\nAnd remember that if you have any questions or tourist information you need, the aparthotel staff speaks several languages and will be happy to help you.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4683b5b elementor-align-left elementor-widget__width-initial elementor-mobile-align-left elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"4683b5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/nelvaresort.com\/en\/aparthotel-en-menorca\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">See Apartments<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2aea166\" data-id=\"2aea166\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1737c0f elementor-widget elementor-widget-image\" data-id=\"1737c0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC04142-683x1024.jpg\" class=\"attachment-large size-large wp-image-4602\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC04142-683x1024.jpg 683w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC04142-200x300.jpg 200w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC04142-768x1152.jpg 768w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC04142-1024x1536.jpg 1024w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC04142-1365x2048.jpg 1365w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC04142-8x12.jpg 8w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC04142-600x900.jpg 600w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC04142-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4e6e9a elementor-reverse-tablet elementor-reverse-mobile elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4e6e9a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bd0c06d\" data-id=\"bd0c06d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bcf5e2 elementor-widget__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image-box\" data-id=\"0bcf5e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">Bar Restaurant with terrace <span style=\"color: var(--ast-global-color-6);font-size: 2.375rem;font-style: inherit;background-color: var(--ast-global-color-4)\"><\/span><br><\/h2><p class=\"elementor-image-box-description\">With an interior room and a large terrace surrounded by gardens next to the pool, it is the perfect place to disconnect while enjoying some Mediterranean tapas or a soft drink, at any time of the day. <br>We also have a varied menu of food that we can prepare for you to take to your apartment, to the beach or on an excursion to the island of Menorca. <br> <br>\n\nYou have at your disposal the incredible breakfast buffet every morning, to start the day with energy. <br><br>\n\nPlus, there&#039;s live music on the terrace! <br>From June to September, we can enjoy Marcos Andr\u00e9s and the show every Monday. <span style=\"letter-spacing: -0.1px\">Thursday<\/span> with Fusiona2.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-693c59b elementor-align-left elementor-widget__width-initial elementor-mobile-align-left elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"693c59b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/en\/reservar\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">book stay<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6cda2a elementor-align-left elementor-widget__width-initial elementor-mobile-align-left elementor-widget-tablet__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"c6cda2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/nelvaresort.com\/en\/bar-restaurante-nelva\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View Restaurant<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5f0b247\" data-id=\"5f0b247\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ac038f elementor-widget elementor-widget-image\" data-id=\"4ac038f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1380-2025-07-08T13_03_31.468-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-4581\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1380-2025-07-08T13_03_31.468-1-1024x683.jpg 1024w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1380-2025-07-08T13_03_31.468-1-300x200.jpg 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1380-2025-07-08T13_03_31.468-1-768x512.jpg 768w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1380-2025-07-08T13_03_31.468-1-1536x1024.jpg 1536w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1380-2025-07-08T13_03_31.468-1-2048x1365.jpg 2048w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1380-2025-07-08T13_03_31.468-1-18x12.jpg 18w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1380-2025-07-08T13_03_31.468-1-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51d84e6 elementor-widget elementor-widget-image\" data-id=\"51d84e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1464-2025-07-08T13_05_11.294-1024x683.jpg\" class=\"attachment-large size-large wp-image-4606\" alt=\"\" srcset=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1464-2025-07-08T13_05_11.294-1024x683.jpg 1024w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1464-2025-07-08T13_05_11.294-300x200.jpg 300w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1464-2025-07-08T13_05_11.294-768x512.jpg 768w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1464-2025-07-08T13_05_11.294-1536x1024.jpg 1536w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1464-2025-07-08T13_05_11.294-2048x1365.jpg 2048w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1464-2025-07-08T13_05_11.294-18x12.jpg 18w, https:\/\/nelvaresort.com\/wp-content\/uploads\/2026\/04\/DSC_1464-2025-07-08T13_05_11.294-600x400.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-05966a2 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"05966a2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99bc75f\" data-id=\"99bc75f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dfadc88 elementor-widget elementor-widget-heading\" data-id=\"dfadc88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Live an unforgettable experience in Menorca<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1ae356 elementor-widget elementor-widget-text-editor\" data-id=\"f1ae356\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Discover one of the most charming islands in the Mediterranean with Nelva Resorts.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8c2beb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c2beb4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a843c5a\" data-id=\"a843c5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44121cc elementor-widget elementor-widget-shortcode\" data-id=\"44121cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n\t\t\t<form id=\"sib_signup_form_5\" method=\"post\" class=\"sib_signup_form\" action=\"\">\n\t\t\t\t<div class=\"sib_loader\" style=\"display:none;\"><img\n\t\t\t\t\t\t\tsrc=\"https:\/\/nelvaresort.com\/wp-includes\/images\/spinner.gif\" alt=\"loader\"><\/div>\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_action\" value=\"subscribe_form_submit\">\n\t\t\t\t<input type=\"hidden\" name=\"sib_form_id\" value=\"5\">\n                <input type=\"hidden\" name=\"sib_form_alert_notice\" value=\"Por favor rellene este campo\">\n                <input type=\"hidden\" name=\"sib_form_invalid_email_notice\" value=\"Tu direcci\u00f3n de correo electr\u00f3nico no es v\u00e1lida\">\n                <input type=\"hidden\" name=\"sib_security\" value=\"5b249829dd\">\n\t\t\t\t<div class=\"sib_signup_box_inside_5\">\n\t\t\t\t\t<div style=\"\/*display:none*\/\" class=\"sib_msg_disp\">\n\t\t\t\t\t<\/div>\n                    \t\t\t\t\t<div style=\"width:100% !important\">\r\n\r\n    <p style=\"display:inline-block\"> \r\n    <label class=\"sib-email-area\"><\/label> \r\n    \r\n    <input placeholder=\"Name\" type=\"text\" class=\"sib-FIRSTNAME-area\" name=\"NAME\">\r\n<input type=\"email\" class=\"sib-email-area\" name=\"email\" placeholder=\"E-mail address\" value=\"\" required=\"required\"> \r\n<\/p>\r\n<p>\r\n<p> \r\n    <label class=\"sib-IDIOMA-area\"><\/label> \r\n    <input id=\"idioma-input\" type=\"text\" class=\"sib-IDIOMA-area\" name=\"IDIOMA\" value=\"es\" required=\"required\"> \r\n<\/p>\r\n<input type=\"checkbox\" name=\"terms\" required=\"required\"> <span style=\"color: #ffffff\">I accept the<a href=\"https:\/\/nelvaresort.com\/en\/politica-de-privacidad\/\"> terms and conditions<\/a>\r\n<\/p><p>\r\n\r\n  <input type=\"submit\" class=\"sib-default-btn\" value=\"Subscribe\">\r\n<\/p>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n\t\t\t<style>\n\t\t\t\tform#sib_signup_form_5 p.sib-alert-message {\n    padding: 6px 12px;\n    margin-bottom: 20px;\n    border: 1px solid transparent;\n    border-radius: 4px;\n    -webkit-box-sizing: border-box;\n    -moz-box-sizing: border-box;\n    box-sizing: border-box;\n}\nform#sib_signup_form_5 p.sib-alert-message-error {\n    background-color: #f2dede;\n    border-color: #ebccd1;\n    color: #a94442;\n}\nform#sib_signup_form_5 p.sib-alert-message-success {\n    background-color: #dff0d8;\n    border-color: #d6e9c6;\n    color: #3c763d;\n}\nform#sib_signup_form_5 p.sib-alert-message-warning {\n    background-color: #fcf8e3;\n    border-color: #faebcc;\n    color: #8a6d3b;\n}\n\t\t\t<\/style>\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Servicios e instalaciones Podr\u00e1s disfrutar de nuestra piscina y zona ajardinada o tomar algo en el Bar Restaurante Nelva Oferta web a partir 5% todos los apartamentos Nelva Resort En Nelva Resort ponemos a tu disposici\u00f3n un entorno agradable y amplio para que puedas disfrutar de tu estancia. Tenemos varios rincones y salas en las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3428,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2880","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servicios e instalaciones | Aparthotel en Menorca | Restaurante<\/title>\n<meta name=\"description\" content=\"Descubre los servicios e instalaciones de Nelva Resort, aparthotel en Menorca: piscina, zonas comunes, comodidad y todo lo necesario para una estancia perfecta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nelvaresort.com\/en\/servicios-e-instalaciones\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servicios e instalaciones | Aparthotel en Menorca | Restaurante\" \/>\n<meta property=\"og:description\" content=\"Descubre los servicios e instalaciones de Nelva Resort, aparthotel en Menorca: piscina, zonas comunes, comodidad y todo lo necesario para una estancia perfecta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nelvaresort.com\/en\/servicios-e-instalaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Nelva Resort | Apartamentos en Menorca | Web Oficial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NelvaResortMenorca\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-01T17:18:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/nelva-quadres-menorca-1-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nelvaresort.com\\\/servicios-e-instalaciones\\\/\",\"url\":\"https:\\\/\\\/nelvaresort.com\\\/servicios-e-instalaciones\\\/\",\"name\":\"Servicios e instalaciones | Aparthotel en Menorca | Restaurante\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nelvaresort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nelvaresort.com\\\/servicios-e-instalaciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nelvaresort.com\\\/servicios-e-instalaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nelvaresort.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/nelva-quadres-menorca-1-scaled-1.jpg\",\"datePublished\":\"2023-06-09T07:23:58+00:00\",\"dateModified\":\"2026-05-01T17:18:55+00:00\",\"description\":\"Descubre los servicios e instalaciones de Nelva Resort, aparthotel en Menorca: piscina, zonas comunes, comodidad y todo lo necesario para una estancia perfecta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nelvaresort.com\\\/servicios-e-instalaciones\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nelvaresort.com\\\/servicios-e-instalaciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/nelvaresort.com\\\/servicios-e-instalaciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nelvaresort.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/nelva-quadres-menorca-1-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/nelvaresort.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/nelva-quadres-menorca-1-scaled-1.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nelvaresort.com\\\/servicios-e-instalaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/nelvaresort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicios e instalaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nelvaresort.com\\\/#website\",\"url\":\"https:\\\/\\\/nelvaresort.com\\\/\",\"name\":\"Aparthotel en Menorca | Nelva Resort\",\"description\":\"Apartamentos en Menorca al mejor precio. Aparthotel ubicado en la playa de Cala\u2019n Porter de Menorca. Reserva aqu\u00ed.\",\"publisher\":{\"@id\":\"https:\\\/\\\/nelvaresort.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nelvaresort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nelvaresort.com\\\/#organization\",\"name\":\"Aparthotel en Menorca | Nelva Resort\",\"url\":\"https:\\\/\\\/nelvaresort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/nelvaresort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nelvaresort.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/nelva-resort-logo.png\",\"contentUrl\":\"https:\\\/\\\/nelvaresort.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/nelva-resort-logo.png\",\"width\":709,\"height\":709,\"caption\":\"Aparthotel en Menorca | Nelva Resort\"},\"image\":{\"@id\":\"https:\\\/\\\/nelvaresort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NelvaResortMenorca\",\"https:\\\/\\\/www.instagram.com\\\/nelvaresortmenorca\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Services and facilities | Aparthotel in Menorca | Restaurant","description":"Discover the services and facilities of Nelva Resort, an aparthotel in Menorca: swimming pool, common areas, comfort and everything you need for a perfect stay.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nelvaresort.com\/en\/servicios-e-instalaciones\/","og_locale":"en_GB","og_type":"article","og_title":"Servicios e instalaciones | Aparthotel en Menorca | Restaurante","og_description":"Descubre los servicios e instalaciones de Nelva Resort, aparthotel en Menorca: piscina, zonas comunes, comodidad y todo lo necesario para una estancia perfecta.","og_url":"https:\/\/nelvaresort.com\/en\/servicios-e-instalaciones\/","og_site_name":"Nelva Resort | Apartamentos en Menorca | Web Oficial","article_publisher":"https:\/\/www.facebook.com\/NelvaResortMenorca","article_modified_time":"2026-05-01T17:18:55+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/nelva-quadres-menorca-1-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nelvaresort.com\/servicios-e-instalaciones\/","url":"https:\/\/nelvaresort.com\/servicios-e-instalaciones\/","name":"Services and facilities | Aparthotel in Menorca | Restaurant","isPartOf":{"@id":"https:\/\/nelvaresort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nelvaresort.com\/servicios-e-instalaciones\/#primaryimage"},"image":{"@id":"https:\/\/nelvaresort.com\/servicios-e-instalaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/nelva-quadres-menorca-1-scaled-1.jpg","datePublished":"2023-06-09T07:23:58+00:00","dateModified":"2026-05-01T17:18:55+00:00","description":"Discover the services and facilities of Nelva Resort, an aparthotel in Menorca: swimming pool, common areas, comfort and everything you need for a perfect stay.","breadcrumb":{"@id":"https:\/\/nelvaresort.com\/servicios-e-instalaciones\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nelvaresort.com\/servicios-e-instalaciones\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/nelvaresort.com\/servicios-e-instalaciones\/#primaryimage","url":"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/nelva-quadres-menorca-1-scaled-1.jpg","contentUrl":"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/09\/nelva-quadres-menorca-1-scaled-1.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/nelvaresort.com\/servicios-e-instalaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/nelvaresort.com\/"},{"@type":"ListItem","position":2,"name":"Servicios e instalaciones"}]},{"@type":"WebSite","@id":"https:\/\/nelvaresort.com\/#website","url":"https:\/\/nelvaresort.com\/","name":"Aparthotel in Menorca | Nelva Resort","description":"Apartments in Menorca at the best price. Aparthotel located on the Cala&#039;n Porter beach in Menorca. Reserve here.","publisher":{"@id":"https:\/\/nelvaresort.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nelvaresort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/nelvaresort.com\/#organization","name":"Aparthotel in Menorca | Nelva Resort","url":"https:\/\/nelvaresort.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/nelvaresort.com\/#\/schema\/logo\/image\/","url":"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/nelva-resort-logo.png","contentUrl":"https:\/\/nelvaresort.com\/wp-content\/uploads\/2023\/06\/nelva-resort-logo.png","width":709,"height":709,"caption":"Aparthotel en Menorca | Nelva Resort"},"image":{"@id":"https:\/\/nelvaresort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NelvaResortMenorca","https:\/\/www.instagram.com\/nelvaresortmenorca\/"]}]}},"_links":{"self":[{"href":"https:\/\/nelvaresort.com\/en\/wp-json\/wp\/v2\/pages\/2880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nelvaresort.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nelvaresort.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nelvaresort.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nelvaresort.com\/en\/wp-json\/wp\/v2\/comments?post=2880"}],"version-history":[{"count":70,"href":"https:\/\/nelvaresort.com\/en\/wp-json\/wp\/v2\/pages\/2880\/revisions"}],"predecessor-version":[{"id":4667,"href":"https:\/\/nelvaresort.com\/en\/wp-json\/wp\/v2\/pages\/2880\/revisions\/4667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nelvaresort.com\/en\/wp-json\/wp\/v2\/media\/3428"}],"wp:attachment":[{"href":"https:\/\/nelvaresort.com\/en\/wp-json\/wp\/v2\/media?parent=2880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}